{"id":348108,"date":"2011-11-24T13:58:00","date_gmt":"2011-11-24T13:58:00","guid":{"rendered":"https:\/\/www.devalken.com\/?p=348108"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"2011-11-24_0158_4552","status":"publish","type":"post","link":"https:\/\/www.devalken.com\/index.php\/2011\/11\/24\/2011-11-24_0158_4552\/","title":{"rendered":"Twitter oproep: Wie twittert mee?"},"content":{"rendered":"<p>Sinds enige tijd heeft DeValken.com een eigen Twitter-account. Aangezien er natuurlijk meerdere wedstrijden in het weekend zijn, er meer rondom het sportieve gebeuren te melden is, hier een verzoek:<\/p>\n<p><b>Wie Twittert mee?<\/b><\/p>\n<p>Indien je mee wenst te Twitteren via het DeValken.com-account worden al onze volgers direct op de hoogte gehouden van het wel een wee van onze vereniging.<\/p>\n<p>Dus als je mee wilt Twitteren, meld je dan even via de mail: <a href=\"mailto:postmaster@devalken.com?subject=ik wil meetwitteren via DeValken.com\"<\/a>postmaster@devalken.com<\/a> en we regelen toegang.<\/p>\n<p>Uiteraard is dit weer een proef: misbruik is niet gewenst!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sinds enige tijd heeft DeValken.com een eigen Twitter-account. Aangezien er natuurlijk meerdere wedstrijden in het weekend zijn, er meer rondom het sportieve gebeuren te melden is, hier een verzoek: Wie Twittert mee? Indien je mee wenst te Twitteren via het DeValken.com-account worden al onze volgers&#8230;<\/p>\n<div class=\"easywp-readmore\"><a class=\"read-more-link\" href=\"https:\/\/www.devalken.com\/index.php\/2011\/11\/24\/2011-11-24_0158_4552\/\">Lees verder &#8230;<span class=\"screen-reader-text\">  Twitter oproep: Wie twittert mee?<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-348108","post","type-post","status-publish","format-standard","hentry","category-algemeen","wpcat-1-id"],"_links":{"self":[{"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/posts\/348108"}],"collection":[{"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/comments?post=348108"}],"version-history":[{"count":0,"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/posts\/348108\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/media?parent=348108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/categories?post=348108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devalken.com\/index.php\/wp-json\/wp\/v2\/tags?post=348108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}